{"id":150,"date":"2011-12-24T10:34:05","date_gmt":"2011-12-24T13:34:05","guid":{"rendered":"https:\/\/www.office365brasil.com.br\/365blog\/office-365\/considerao-importante-uso-do-office-365\/"},"modified":"2011-12-24T10:34:05","modified_gmt":"2011-12-24T13:34:05","slug":"considerao-importante-uso-do-office-365","status":"publish","type":"post","link":"https:\/\/www.office365brasil.com.br\/365blog\/office-365\/considerao-importante-uso-do-office-365\/","title":{"rendered":"Considera\u00e7\u00e3o importante no uso do Office 365"},"content":{"rendered":"<blockquote><p>Quero usar este breve post para fazer uma considera\u00e7\u00e3o bastante importante para quem est\u00e1 usando ou avaliando o uso do <a href=\"http:\/\/www.office365brasil.com.br\">Office 365<\/a> em seu ambiente. Ela esta relacionada a um aspecto essencial do uso da solu\u00e7\u00e3o e n\u00e3o tem muito relacionado com o <a href=\"http:\/\/www.office365brasil.com.br\">Office 365<\/a> em si,\u00a0 seus recursos, garantias, suporte e uso geral.<\/p>\n<p>Na verdade isso tem mais que ver com uma escolha da sua empresa ou sua mesmo. O servidor de hospedagem para o seu dom\u00ednio que ser\u00e1 utilizado no <a href=\"http:\/\/www.office365brasil.com.br\">Office 365<\/a>. Este \u00e9 um aspecto essencial e vai garantir ou n\u00e3o o sucesso do uso do Office 365 em seu ambiente. Caso voc\u00ea escolha o servi\u00e7o errado para hospedar o seu dom\u00ednio vai ter muitos problemas.<\/p>\n<p>Um dos aspectos mais importantes esta relacionado a garantia de continuidade do servi\u00e7os. Cobre do seu provedor um SLA no m\u00ednimo igual ao oferecido pelo Office 365: 99,9%. N\u00e3o vai adiantar nada ter um servi\u00e7o de classe corporativa como o <a href=\"http:\/\/www.office365brasil.com.br\">Office 365<\/a> e ao mesmo tempo usar um servidor de hospedagem que na verdade \u00e9 uma revenda de algu\u00e9m que n\u00e3o sabe trabalhar de maneira eficiente, e pior um host que esta fora do ar constantemente.<\/p>\n<p>N\u00e3o economize neste aspecto, existem bons servi\u00e7os tanto no Brasil como tamb\u00e9m l\u00e1 fora. Pesquise leia o contrato de servi\u00e7o e esteja preparado para pagar por um servi\u00e7o o mais dispon\u00edvel poss\u00edvel, afinal voc\u00ea ir\u00e1 colocar servi\u00e7os essenciais como e-mail totalmente dependentes destes provedores de hospedagem.<\/p>\n<p>Outro aspecto \u00e9 controle. Tenha acesso as configura\u00e7\u00f5es de DNS para que voc\u00ea possa efetuar as configura\u00e7\u00f5es dos registros necess\u00e1rios para o uso das solu\u00e7\u00f5es que fazem parte do <a href=\"http:\/\/www.office365brasil.com.br\">Office 365<\/a>. Existem alguns provedores que n\u00e3o fornecem este acesso e tornam voc\u00ea dependente da administra\u00e7\u00e3o deles. N\u00e3o escolha servi\u00e7os assim.<\/p>\n<p>Contratando o servi\u00e7o correto voc\u00ea tem menos uma preocupa\u00e7\u00e3o. Mas lembre-se de fazer valer o seu direito. Exija aperfei\u00e7oamentos, alta disponibilidade e melhorias que ir\u00e3o refletir em mais tranquilidade para voc\u00ea.<\/p><\/blockquote>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Quero usar este breve post para fazer uma considera\u00e7\u00e3o bastante importante para quem est\u00e1 usando ou avaliando o uso do<!-- AddThis Advanced Settings generic via filter on wp_trim_excerpt --><!-- AddThis Share Buttons generic via filter on wp_trim_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[8],"tags":[66,96,166],"class_list":["post-150","post","type-post","status-publish","format-standard","hentry","category-office-365","tag-dns","tag-hospedagem","tag-seguranca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Considera\u00e7\u00e3o importante no uso do Office 365 - 365Brasil Blog - Novidades sobre o Microsoft 365<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.office365brasil.com.br\/365blog\/office-365\/considerao-importante-uso-do-office-365\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Considera\u00e7\u00e3o importante no uso do Office 365 - 365Brasil Blog - Novidades sobre o Microsoft 365\" \/>\n<meta property=\"og:description\" content=\"Quero usar este breve post para fazer uma considera\u00e7\u00e3o bastante importante para quem est\u00e1 usando ou avaliando o uso do\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.office365brasil.com.br\/365blog\/office-365\/considerao-importante-uso-do-office-365\/\" \/>\n<meta property=\"og:site_name\" content=\"365Brasil Blog - Novidades sobre o Microsoft 365\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/helinton.dias\" \/>\n<meta property=\"article:published_time\" content=\"2011-12-24T13:34:05+00:00\" \/>\n<meta name=\"author\" content=\"Helinton\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@helintondias\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helinton\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/office-365\\\/considerao-importante-uso-do-office-365\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/office-365\\\/considerao-importante-uso-do-office-365\\\/\"},\"author\":{\"name\":\"Helinton\",\"@id\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/#\\\/schema\\\/person\\\/5eecfa02cb728635087ffe1dd1c14682\"},\"headline\":\"Considera\u00e7\u00e3o importante no uso do Office 365\",\"datePublished\":\"2011-12-24T13:34:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/office-365\\\/considerao-importante-uso-do-office-365\\\/\"},\"wordCount\":351,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/#organization\"},\"keywords\":[\"dns\",\"hospedagem\",\"seguran\u00e7a\"],\"articleSection\":[\"Office 365\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/office-365\\\/considerao-importante-uso-do-office-365\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/office-365\\\/considerao-importante-uso-do-office-365\\\/\",\"url\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/office-365\\\/considerao-importante-uso-do-office-365\\\/\",\"name\":\"Considera\u00e7\u00e3o importante no uso do Office 365 - 365Brasil Blog - Novidades sobre o Microsoft 365\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/#website\"},\"datePublished\":\"2011-12-24T13:34:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/office-365\\\/considerao-importante-uso-do-office-365\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/office-365\\\/considerao-importante-uso-do-office-365\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/office-365\\\/considerao-importante-uso-do-office-365\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Considera\u00e7\u00e3o importante no uso do Office 365\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/#website\",\"url\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/\",\"name\":\"365Brasil Blog - Novidades sobre o Microsoft 365\",\"description\":\"Novidades e artigos relacionados sobre o Microsoft 365\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/#organization\",\"name\":\"365Brasil Blog - Novidades sobre o Microsoft 365\",\"url\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo.png\",\"width\":318,\"height\":65,\"caption\":\"365Brasil Blog - Novidades sobre o Microsoft 365\"},\"image\":{\"@id\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/#\\\/schema\\\/person\\\/5eecfa02cb728635087ffe1dd1c14682\",\"name\":\"Helinton\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e94f64dc2d8245c43543b261db6f23bfc05b72d7e346b2d603e02e1d6006a039?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e94f64dc2d8245c43543b261db6f23bfc05b72d7e346b2d603e02e1d6006a039?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e94f64dc2d8245c43543b261db6f23bfc05b72d7e346b2d603e02e1d6006a039?s=96&d=mm&r=g\",\"caption\":\"Helinton\"},\"description\":\"Gerente comercial na empresa CloudExperts parceiro Microsoft focado em solu\u00e7\u00f5es de nuvem p\u00fablica para o mercado de pequenas e m\u00e9dias empresas.\",\"sameAs\":[\"https:\\\/\\\/plus.google.com\\\/u\\\/0\\\/+HelintonDias\",\"https:\\\/\\\/www.facebook.com\\\/helinton.dias\",\"https:\\\/\\\/x.com\\\/helintondias\"],\"url\":\"https:\\\/\\\/www.office365brasil.com.br\\\/365blog\\\/author\\\/helinton\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Considera\u00e7\u00e3o importante no uso do Office 365 - 365Brasil Blog - Novidades sobre o Microsoft 365","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.office365brasil.com.br\/365blog\/office-365\/considerao-importante-uso-do-office-365\/","og_locale":"pt_BR","og_type":"article","og_title":"Considera\u00e7\u00e3o importante no uso do Office 365 - 365Brasil Blog - Novidades sobre o Microsoft 365","og_description":"Quero usar este breve post para fazer uma considera\u00e7\u00e3o bastante importante para quem est\u00e1 usando ou avaliando o uso do","og_url":"https:\/\/www.office365brasil.com.br\/365blog\/office-365\/considerao-importante-uso-do-office-365\/","og_site_name":"365Brasil Blog - Novidades sobre o Microsoft 365","article_author":"https:\/\/www.facebook.com\/helinton.dias","article_published_time":"2011-12-24T13:34:05+00:00","author":"Helinton","twitter_card":"summary_large_image","twitter_creator":"@helintondias","twitter_misc":{"Escrito por":"Helinton","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.office365brasil.com.br\/365blog\/office-365\/considerao-importante-uso-do-office-365\/#article","isPartOf":{"@id":"https:\/\/www.office365brasil.com.br\/365blog\/office-365\/considerao-importante-uso-do-office-365\/"},"author":{"name":"Helinton","@id":"https:\/\/www.office365brasil.com.br\/365blog\/#\/schema\/person\/5eecfa02cb728635087ffe1dd1c14682"},"headline":"Considera\u00e7\u00e3o importante no uso do Office 365","datePublished":"2011-12-24T13:34:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.office365brasil.com.br\/365blog\/office-365\/considerao-importante-uso-do-office-365\/"},"wordCount":351,"commentCount":0,"publisher":{"@id":"https:\/\/www.office365brasil.com.br\/365blog\/#organization"},"keywords":["dns","hospedagem","seguran\u00e7a"],"articleSection":["Office 365"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.office365brasil.com.br\/365blog\/office-365\/considerao-importante-uso-do-office-365\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.office365brasil.com.br\/365blog\/office-365\/considerao-importante-uso-do-office-365\/","url":"https:\/\/www.office365brasil.com.br\/365blog\/office-365\/considerao-importante-uso-do-office-365\/","name":"Considera\u00e7\u00e3o importante no uso do Office 365 - 365Brasil Blog - Novidades sobre o Microsoft 365","isPartOf":{"@id":"https:\/\/www.office365brasil.com.br\/365blog\/#website"},"datePublished":"2011-12-24T13:34:05+00:00","breadcrumb":{"@id":"https:\/\/www.office365brasil.com.br\/365blog\/office-365\/considerao-importante-uso-do-office-365\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.office365brasil.com.br\/365blog\/office-365\/considerao-importante-uso-do-office-365\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.office365brasil.com.br\/365blog\/office-365\/considerao-importante-uso-do-office-365\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.office365brasil.com.br\/365blog\/"},{"@type":"ListItem","position":2,"name":"Considera\u00e7\u00e3o importante no uso do Office 365"}]},{"@type":"WebSite","@id":"https:\/\/www.office365brasil.com.br\/365blog\/#website","url":"https:\/\/www.office365brasil.com.br\/365blog\/","name":"365Brasil Blog - Novidades sobre o Microsoft 365","description":"Novidades e artigos relacionados sobre o Microsoft 365","publisher":{"@id":"https:\/\/www.office365brasil.com.br\/365blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.office365brasil.com.br\/365blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.office365brasil.com.br\/365blog\/#organization","name":"365Brasil Blog - Novidades sobre o Microsoft 365","url":"https:\/\/www.office365brasil.com.br\/365blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.office365brasil.com.br\/365blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.office365brasil.com.br\/365blog\/wp-content\/uploads\/2021\/04\/logo.png","contentUrl":"https:\/\/www.office365brasil.com.br\/365blog\/wp-content\/uploads\/2021\/04\/logo.png","width":318,"height":65,"caption":"365Brasil Blog - Novidades sobre o Microsoft 365"},"image":{"@id":"https:\/\/www.office365brasil.com.br\/365blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.office365brasil.com.br\/365blog\/#\/schema\/person\/5eecfa02cb728635087ffe1dd1c14682","name":"Helinton","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e94f64dc2d8245c43543b261db6f23bfc05b72d7e346b2d603e02e1d6006a039?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e94f64dc2d8245c43543b261db6f23bfc05b72d7e346b2d603e02e1d6006a039?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e94f64dc2d8245c43543b261db6f23bfc05b72d7e346b2d603e02e1d6006a039?s=96&d=mm&r=g","caption":"Helinton"},"description":"Gerente comercial na empresa CloudExperts parceiro Microsoft focado em solu\u00e7\u00f5es de nuvem p\u00fablica para o mercado de pequenas e m\u00e9dias empresas.","sameAs":["https:\/\/plus.google.com\/u\/0\/+HelintonDias","https:\/\/www.facebook.com\/helinton.dias","https:\/\/x.com\/helintondias"],"url":"https:\/\/www.office365brasil.com.br\/365blog\/author\/helinton\/"}]}},"_links":{"self":[{"href":"https:\/\/www.office365brasil.com.br\/365blog\/wp-json\/wp\/v2\/posts\/150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.office365brasil.com.br\/365blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.office365brasil.com.br\/365blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.office365brasil.com.br\/365blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.office365brasil.com.br\/365blog\/wp-json\/wp\/v2\/comments?post=150"}],"version-history":[{"count":0,"href":"https:\/\/www.office365brasil.com.br\/365blog\/wp-json\/wp\/v2\/posts\/150\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.office365brasil.com.br\/365blog\/wp-json\/wp\/v2\/media?parent=150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.office365brasil.com.br\/365blog\/wp-json\/wp\/v2\/categories?post=150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.office365brasil.com.br\/365blog\/wp-json\/wp\/v2\/tags?post=150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}